{"id":237,"date":"2018-04-12T16:37:35","date_gmt":"2018-04-12T19:37:35","guid":{"rendered":"https:\/\/www.elase.com.br\/blog\/?p=237"},"modified":"2018-07-23T13:36:58","modified_gmt":"2018-07-23T16:36:58","slug":"quer-ser-associado-da-elase-veja-como-fazer-parte-do-clube","status":"publish","type":"post","link":"https:\/\/www.elase.com.br\/blog\/quer-ser-associado-da-elase-veja-como-fazer-parte-do-clube\/","title":{"rendered":"Quer ser associado da Elase? Veja como fazer parte do clube"},"content":{"rendered":"<p>Fazer parte da Elase \u00e9 mais f\u00e1cil do que voc\u00ea imagina! Qualquer pessoa com mais de 18 anos pode se associar ao Clube. Basta <a href=\"\/\/www.elase.com.br\/quero-me-associar\/\" target=\"_blank\" rel=\"noopener\">preencher a ficha cadastral<\/a> no ambiente \u201cQUERO ME ASSOCIAR\u201d do site e \u00a0apresentar os seguintes documentos:<\/p>\n<p>\u00bb C\u00f3pia da Certid\u00e3o de Casamento ou de declara\u00e7\u00e3o de uni\u00e3o est\u00e1vel reconhecida em cart\u00f3rio, com duas testemunhas, para quem vive matrimonialmente. Para os(as) solteiros(as), c\u00f3pia da carteira de identidade;<\/p>\n<p>\u00bb Dependentes: Pai, m\u00e3e, sogro ou sogra (se forem vi\u00favos) e desde que vivam em companhia do(a) associado(a), c\u00f4njuge com comprova\u00e7\u00e3o legal, filhos solteiros at\u00e9 24 anos, e todos aqueles aqui n\u00e3o enquadrados, mas aceitos como dependentes pelo INSS;<\/p>\n<p>\u00bb C\u00f3pia Certid\u00e3o de Nascimento ou do documento de identidade dos filhos.<\/p>\n<p>Ap\u00f3s preenchimento da ficha cadastral, o Clube entrar\u00e1 em contato para finalizar o cadastro e indicar o pagamento da Taxa de Inscri\u00e7\u00e3o.<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"size-full wp-image-299 aligncenter\" src=\"https:\/\/www.elase.com.br\/blog\/wp-content\/uploads\/sites\/2\/2018\/04\/post-elase-associados-desconto.png\" alt=\"\" width=\"800\" height=\"495\" srcset=\"https:\/\/www.elase.com.br\/blog\/wp-content\/uploads\/sites\/2\/2018\/04\/post-elase-associados-desconto.png 800w, https:\/\/www.elase.com.br\/blog\/wp-content\/uploads\/sites\/2\/2018\/04\/post-elase-associados-desconto-300x186.png 300w, https:\/\/www.elase.com.br\/blog\/wp-content\/uploads\/sites\/2\/2018\/04\/post-elase-associados-desconto-768x475.png 768w, https:\/\/www.elase.com.br\/blog\/wp-content\/uploads\/sites\/2\/2018\/04\/post-elase-associados-desconto-230x142.png 230w, https:\/\/www.elase.com.br\/blog\/wp-content\/uploads\/sites\/2\/2018\/04\/post-elase-associados-desconto-350x217.png 350w, https:\/\/www.elase.com.br\/blog\/wp-content\/uploads\/sites\/2\/2018\/04\/post-elase-associados-desconto-480x297.png 480w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p><strong>VANTAGENS DE SER ASSOCIADO DA ELASE<\/strong><\/p>\n<p>Associados \u00e0 Elase podem desfrutar da infraestrutura e das instala\u00e7\u00f5es do Clube, como <a href=\"\/\/www.elase.com.br\/blog\/piscina-elase\/\" target=\"_blank\" rel=\"noopener\">parque aqu\u00e1tico<\/a>, restaurante, bar, playground, salas de jogos, quiosques e sal\u00f5es para festas e eventos, quadras esportivas, sauna, campo de futebol su\u00ed\u00e7o, quadras de t\u00eanis, squash, p\u00e1del, estacionamento, e a sede praia, <a href=\"\/\/www.elase.com.br\/blog\/sede-de-praia-elase-atividades-para-a-familia-o-ano-inteiro\/\" target=\"_blank\" rel=\"noopener\">com camping, na Barra da Lagoa<\/a>.<\/p>\n<p>Al\u00e9m da estrutura, o Clube oferece aulas \/ escolinhas de esportes coletivos, dan\u00e7as, artes marciais, m\u00fasica e artes. S\u00e3o mais de 30 cursos para toda a fam\u00edlia, em turmas de crian\u00e7as, jovens, adultos e idosos com pre\u00e7os abaixo dos oferecidos por outras academias, escolas ou institui\u00e7\u00f5es.<\/p>\n<p>Ainda dentro das instala\u00e7\u00f5es da Elase s\u00e3o oferecidos servi\u00e7os terceirizados como fisioterapia, odontologia, podologia, sal\u00e3o de beleza, lava carros, entre outros.<\/p>\n<p><a href=\"\/\/www.elase.com.br\/quero-me-associar\/\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" class=\"size-full wp-image-240 aligncenter\" src=\"\/\/www.elase.com.br\/blog\/wp-content\/uploads\/sites\/2\/2018\/04\/post-elase-associados-CTA.png\" alt=\"\" width=\"804\" height=\"204\" srcset=\"https:\/\/www.elase.com.br\/blog\/wp-content\/uploads\/sites\/2\/2018\/04\/post-elase-associados-CTA.png 804w, https:\/\/www.elase.com.br\/blog\/wp-content\/uploads\/sites\/2\/2018\/04\/post-elase-associados-CTA-300x76.png 300w, https:\/\/www.elase.com.br\/blog\/wp-content\/uploads\/sites\/2\/2018\/04\/post-elase-associados-CTA-768x195.png 768w, https:\/\/www.elase.com.br\/blog\/wp-content\/uploads\/sites\/2\/2018\/04\/post-elase-associados-CTA-230x58.png 230w, https:\/\/www.elase.com.br\/blog\/wp-content\/uploads\/sites\/2\/2018\/04\/post-elase-associados-CTA-350x89.png 350w, https:\/\/www.elase.com.br\/blog\/wp-content\/uploads\/sites\/2\/2018\/04\/post-elase-associados-CTA-480x122.png 480w\" sizes=\"(max-width: 804px) 100vw, 804px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Fazer parte da Elase \u00e9 mais f\u00e1cil do que voc\u00ea imagina! Qualquer pessoa com mais de 18 anos pode se associar ao [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":241,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[8],"tags":[],"class_list":["post-237","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-elase"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Quer ser associado da Elase? Veja como fazer parte do clube<\/title>\n<meta name=\"description\" content=\"Ser associado da Elase, tradicional clube de Florian\u00f3polis, \u00e9 mais f\u00e1cil do que voc\u00ea imagina. Confira no nosso blog todos os passos para tornar-se\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.elase.com.br\/blog\/quer-ser-associado-da-elase-veja-como-fazer-parte-do-clube\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Quer ser associado da Elase? Veja como fazer parte do clube\" \/>\n<meta property=\"og:description\" content=\"Ser associado da Elase, tradicional clube de Florian\u00f3polis, \u00e9 mais f\u00e1cil do que voc\u00ea imagina. Confira no nosso blog todos os passos para tornar-se\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.elase.com.br\/blog\/quer-ser-associado-da-elase-veja-como-fazer-parte-do-clube\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog da ELASE\" \/>\n<meta property=\"article:published_time\" content=\"2018-04-12T19:37:35+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-07-23T16:36:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.elase.com.br\/blog\/wp-content\/uploads\/sites\/2\/2018\/04\/post-elase-associados-CAPA.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1199\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Elase\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Elase\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.elase.com.br\\\/blog\\\/quer-ser-associado-da-elase-veja-como-fazer-parte-do-clube\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.elase.com.br\\\/blog\\\/quer-ser-associado-da-elase-veja-como-fazer-parte-do-clube\\\/\"},\"author\":{\"name\":\"Elase\",\"@id\":\"https:\\\/\\\/www.elase.com.br\\\/blog\\\/#\\\/schema\\\/person\\\/c5648edcd86e91cabc5f62555421edce\"},\"headline\":\"Quer ser associado da Elase? Veja como fazer parte do clube\",\"datePublished\":\"2018-04-12T19:37:35+00:00\",\"dateModified\":\"2018-07-23T16:36:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.elase.com.br\\\/blog\\\/quer-ser-associado-da-elase-veja-como-fazer-parte-do-clube\\\/\"},\"wordCount\":309,\"image\":{\"@id\":\"https:\\\/\\\/www.elase.com.br\\\/blog\\\/quer-ser-associado-da-elase-veja-como-fazer-parte-do-clube\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.elase.com.br\\\/blog\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/04\\\/post-elase-associados-CAPA.png\",\"articleSection\":[\"ELASE\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.elase.com.br\\\/blog\\\/quer-ser-associado-da-elase-veja-como-fazer-parte-do-clube\\\/\",\"url\":\"https:\\\/\\\/www.elase.com.br\\\/blog\\\/quer-ser-associado-da-elase-veja-como-fazer-parte-do-clube\\\/\",\"name\":\"Quer ser associado da Elase? Veja como fazer parte do clube\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.elase.com.br\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.elase.com.br\\\/blog\\\/quer-ser-associado-da-elase-veja-como-fazer-parte-do-clube\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.elase.com.br\\\/blog\\\/quer-ser-associado-da-elase-veja-como-fazer-parte-do-clube\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.elase.com.br\\\/blog\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/04\\\/post-elase-associados-CAPA.png\",\"datePublished\":\"2018-04-12T19:37:35+00:00\",\"dateModified\":\"2018-07-23T16:36:58+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.elase.com.br\\\/blog\\\/#\\\/schema\\\/person\\\/c5648edcd86e91cabc5f62555421edce\"},\"description\":\"Ser associado da Elase, tradicional clube de Florian\u00f3polis, \u00e9 mais f\u00e1cil do que voc\u00ea imagina. Confira no nosso blog todos os passos para tornar-se parte do clube.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.elase.com.br\\\/blog\\\/quer-ser-associado-da-elase-veja-como-fazer-parte-do-clube\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.elase.com.br\\\/blog\\\/quer-ser-associado-da-elase-veja-como-fazer-parte-do-clube\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.elase.com.br\\\/blog\\\/quer-ser-associado-da-elase-veja-como-fazer-parte-do-clube\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.elase.com.br\\\/blog\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/04\\\/post-elase-associados-CAPA.png\",\"contentUrl\":\"https:\\\/\\\/www.elase.com.br\\\/blog\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/04\\\/post-elase-associados-CAPA.png\",\"width\":1199,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.elase.com.br\\\/blog\\\/quer-ser-associado-da-elase-veja-como-fazer-parte-do-clube\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.elase.com.br\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Quer ser associado da Elase? Veja como fazer parte do clube\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.elase.com.br\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.elase.com.br\\\/blog\\\/\",\"name\":\"Blog da ELASE\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.elase.com.br\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.elase.com.br\\\/blog\\\/#\\\/schema\\\/person\\\/c5648edcd86e91cabc5f62555421edce\",\"name\":\"Elase\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e04f303593dd0bee5fdbdc05ef63066d59e1a5bf61b911bf6653c92bfb86e392?s=96&r=g&d=https:\\\/\\\/www.elase.com.br\\\/blog\\\/wp-content\\\/plugins\\\/userswp\\\/assets\\\/images\\\/no_profile.png\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e04f303593dd0bee5fdbdc05ef63066d59e1a5bf61b911bf6653c92bfb86e392?s=96&r=g&d=https:\\\/\\\/www.elase.com.br\\\/blog\\\/wp-content\\\/plugins\\\/userswp\\\/assets\\\/images\\\/no_profile.png\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e04f303593dd0bee5fdbdc05ef63066d59e1a5bf61b911bf6653c92bfb86e392?s=96&r=g&d=https:\\\/\\\/www.elase.com.br\\\/blog\\\/wp-content\\\/plugins\\\/userswp\\\/assets\\\/images\\\/no_profile.png\",\"caption\":\"Elase\"},\"url\":\"https:\\\/\\\/www.elase.com.br\\\/blog\\\/author\\\/roberta\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Quer ser associado da Elase? Veja como fazer parte do clube","description":"Ser associado da Elase, tradicional clube de Florian\u00f3polis, \u00e9 mais f\u00e1cil do que voc\u00ea imagina. Confira no nosso blog todos os passos para tornar-se","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.elase.com.br\/blog\/quer-ser-associado-da-elase-veja-como-fazer-parte-do-clube\/","og_locale":"pt_BR","og_type":"article","og_title":"Quer ser associado da Elase? Veja como fazer parte do clube","og_description":"Ser associado da Elase, tradicional clube de Florian\u00f3polis, \u00e9 mais f\u00e1cil do que voc\u00ea imagina. Confira no nosso blog todos os passos para tornar-se","og_url":"https:\/\/www.elase.com.br\/blog\/quer-ser-associado-da-elase-veja-como-fazer-parte-do-clube\/","og_site_name":"Blog da ELASE","article_published_time":"2018-04-12T19:37:35+00:00","article_modified_time":"2018-07-23T16:36:58+00:00","og_image":[{"width":1199,"height":630,"url":"https:\/\/www.elase.com.br\/blog\/wp-content\/uploads\/sites\/2\/2018\/04\/post-elase-associados-CAPA.png","type":"image\/png"}],"author":"Elase","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Elase","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.elase.com.br\/blog\/quer-ser-associado-da-elase-veja-como-fazer-parte-do-clube\/#article","isPartOf":{"@id":"https:\/\/www.elase.com.br\/blog\/quer-ser-associado-da-elase-veja-como-fazer-parte-do-clube\/"},"author":{"name":"Elase","@id":"https:\/\/www.elase.com.br\/blog\/#\/schema\/person\/c5648edcd86e91cabc5f62555421edce"},"headline":"Quer ser associado da Elase? Veja como fazer parte do clube","datePublished":"2018-04-12T19:37:35+00:00","dateModified":"2018-07-23T16:36:58+00:00","mainEntityOfPage":{"@id":"https:\/\/www.elase.com.br\/blog\/quer-ser-associado-da-elase-veja-como-fazer-parte-do-clube\/"},"wordCount":309,"image":{"@id":"https:\/\/www.elase.com.br\/blog\/quer-ser-associado-da-elase-veja-como-fazer-parte-do-clube\/#primaryimage"},"thumbnailUrl":"https:\/\/www.elase.com.br\/blog\/wp-content\/uploads\/sites\/2\/2018\/04\/post-elase-associados-CAPA.png","articleSection":["ELASE"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/www.elase.com.br\/blog\/quer-ser-associado-da-elase-veja-como-fazer-parte-do-clube\/","url":"https:\/\/www.elase.com.br\/blog\/quer-ser-associado-da-elase-veja-como-fazer-parte-do-clube\/","name":"Quer ser associado da Elase? Veja como fazer parte do clube","isPartOf":{"@id":"https:\/\/www.elase.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.elase.com.br\/blog\/quer-ser-associado-da-elase-veja-como-fazer-parte-do-clube\/#primaryimage"},"image":{"@id":"https:\/\/www.elase.com.br\/blog\/quer-ser-associado-da-elase-veja-como-fazer-parte-do-clube\/#primaryimage"},"thumbnailUrl":"https:\/\/www.elase.com.br\/blog\/wp-content\/uploads\/sites\/2\/2018\/04\/post-elase-associados-CAPA.png","datePublished":"2018-04-12T19:37:35+00:00","dateModified":"2018-07-23T16:36:58+00:00","author":{"@id":"https:\/\/www.elase.com.br\/blog\/#\/schema\/person\/c5648edcd86e91cabc5f62555421edce"},"description":"Ser associado da Elase, tradicional clube de Florian\u00f3polis, \u00e9 mais f\u00e1cil do que voc\u00ea imagina. Confira no nosso blog todos os passos para tornar-se parte do clube.","breadcrumb":{"@id":"https:\/\/www.elase.com.br\/blog\/quer-ser-associado-da-elase-veja-como-fazer-parte-do-clube\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.elase.com.br\/blog\/quer-ser-associado-da-elase-veja-como-fazer-parte-do-clube\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.elase.com.br\/blog\/quer-ser-associado-da-elase-veja-como-fazer-parte-do-clube\/#primaryimage","url":"https:\/\/www.elase.com.br\/blog\/wp-content\/uploads\/sites\/2\/2018\/04\/post-elase-associados-CAPA.png","contentUrl":"https:\/\/www.elase.com.br\/blog\/wp-content\/uploads\/sites\/2\/2018\/04\/post-elase-associados-CAPA.png","width":1199,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/www.elase.com.br\/blog\/quer-ser-associado-da-elase-veja-como-fazer-parte-do-clube\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.elase.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Quer ser associado da Elase? Veja como fazer parte do clube"}]},{"@type":"WebSite","@id":"https:\/\/www.elase.com.br\/blog\/#website","url":"https:\/\/www.elase.com.br\/blog\/","name":"Blog da ELASE","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.elase.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/www.elase.com.br\/blog\/#\/schema\/person\/c5648edcd86e91cabc5f62555421edce","name":"Elase","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/e04f303593dd0bee5fdbdc05ef63066d59e1a5bf61b911bf6653c92bfb86e392?s=96&r=g&d=https:\/\/www.elase.com.br\/blog\/wp-content\/plugins\/userswp\/assets\/images\/no_profile.png","url":"https:\/\/secure.gravatar.com\/avatar\/e04f303593dd0bee5fdbdc05ef63066d59e1a5bf61b911bf6653c92bfb86e392?s=96&r=g&d=https:\/\/www.elase.com.br\/blog\/wp-content\/plugins\/userswp\/assets\/images\/no_profile.png","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e04f303593dd0bee5fdbdc05ef63066d59e1a5bf61b911bf6653c92bfb86e392?s=96&r=g&d=https:\/\/www.elase.com.br\/blog\/wp-content\/plugins\/userswp\/assets\/images\/no_profile.png","caption":"Elase"},"url":"https:\/\/www.elase.com.br\/blog\/author\/roberta\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-07-22 14:41:28","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.elase.com.br\/blog\/wp-json\/wp\/v2\/posts\/237","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.elase.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.elase.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.elase.com.br\/blog\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.elase.com.br\/blog\/wp-json\/wp\/v2\/comments?post=237"}],"version-history":[{"count":5,"href":"https:\/\/www.elase.com.br\/blog\/wp-json\/wp\/v2\/posts\/237\/revisions"}],"predecessor-version":[{"id":300,"href":"https:\/\/www.elase.com.br\/blog\/wp-json\/wp\/v2\/posts\/237\/revisions\/300"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.elase.com.br\/blog\/wp-json\/wp\/v2\/media\/241"}],"wp:attachment":[{"href":"https:\/\/www.elase.com.br\/blog\/wp-json\/wp\/v2\/media?parent=237"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.elase.com.br\/blog\/wp-json\/wp\/v2\/categories?post=237"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.elase.com.br\/blog\/wp-json\/wp\/v2\/tags?post=237"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}