{"id":1072,"date":"2023-03-16T11:25:35","date_gmt":"2023-03-16T14:25:35","guid":{"rendered":"https:\/\/www.elase.com.br\/blog\/?p=1072"},"modified":"2023-03-24T12:03:23","modified_gmt":"2023-03-24T15:03:23","slug":"eleicoes-elase-2023-2026-comunicado-3","status":"publish","type":"post","link":"https:\/\/www.elase.com.br\/blog\/eleicoes-elase-2023-2026-comunicado-3\/","title":{"rendered":"Elei\u00e7\u00f5es ELASE \u2013 2023\/2026: COMUNICADO 3"},"content":{"rendered":"<p>A COMISS\u00c3O ELEITORAL designada pelo Conselho Deliberativo da ELASE, nos termos do Regulamento Geral das Elei\u00e7\u00f5es, comunica aos associados que no dia 14\/03\/2023, \u00e0s 18h, foram encerradas as inscri\u00e7\u00f5es dos interessados em concorrer \u00e0s Elei\u00e7\u00f5es para tri\u00eanio 2023-2026.<\/p>\n<p>Dando observ\u00e2ncia ao estabelecido no cap\u00edtulo II &#8211; PEDIDO DE REGISTRO, do Regulamento Geral das Elei\u00e7\u00f5es, os formul\u00e1rios de inscri\u00e7\u00e3o das referidas candidaturas est\u00e3o \u00e0 disposi\u00e7\u00e3o na secretaria do Clube, para eventuais averigua\u00e7\u00f5es e\/ou contesta\u00e7\u00f5es dos associados.<\/p>\n<p>Ap\u00f3s observado a categoria dos associados (fundador ou a ele equiparados), se est\u00e3o adimplentes com as contribui\u00e7\u00f5es pecuni\u00e1rias na ELASE e a verifica\u00e7\u00e3o da inscri\u00e7\u00e3o para um \u00fanico cargo, ou seja, Diretoria Executiva, Conselho Deliberativo ou Conselho Fiscal, apresentamos abaixo a rela\u00e7\u00e3o das candidaturas e seus respectivos cargos:<\/p>\n<ol>\n<li>a) Diretoria Executiva<\/li>\n<\/ol>\n<table style=\"width: 100%; height: 480px;\">\n<tbody>\n<tr style=\"height: 80px;\">\n<td style=\"width: 16.6378%; height: 80px;\"><b>Chapa<\/b><\/td>\n<td style=\"width: 59.2721%; height: 80px;\"><b>Composi\u00e7\u00e3o<\/b><\/td>\n<td style=\"width: 22.357%; height: 80px;\">\n<p style=\"text-align: center;\"><b>Matr\u00edcula ELASE<\/b><\/p>\n<\/td>\n<\/tr>\n<tr style=\"height: 96px;\">\n<td style=\"width: 16.6378%; height: 400px;\" rowspan=\"6\">Juntos Somos +<\/td>\n<td style=\"width: 59.2721%; height: 96px;\">Presidente: Ant\u00f4nio Sim\u00f5es Neto<\/p>\n<p>&nbsp;<\/td>\n<td style=\"width: 22.357%; text-align: right; height: 96px;\">\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 538<\/td>\n<\/tr>\n<tr style=\"height: 56px;\">\n<td style=\"width: 59.2721%; height: 56px;\">Vice-presidente: Lu\u00eds Roberto de Oliveira<\/td>\n<td style=\"width: 22.357%; text-align: right; height: 56px;\">\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 3748<\/td>\n<\/tr>\n<tr style=\"height: 80px;\">\n<td style=\"width: 59.2721%; height: 80px;\">Diretoria Administrativa e Financeira: Janildo Jovino da Silveira<\/td>\n<td style=\"width: 22.357%; text-align: right; height: 80px;\">\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 3205<\/td>\n<\/tr>\n<tr style=\"height: 56px;\">\n<td style=\"width: 59.2721%; height: 56px;\">Diretoria de Esportes: Paulo C\u00edcero Barbosa<\/td>\n<td style=\"width: 22.357%; text-align: right; height: 56px;\">\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 3601<\/td>\n<\/tr>\n<tr style=\"height: 56px;\">\n<td style=\"width: 59.2721%; height: 56px;\">Diretoria Social: Jos\u00e9 Paulo Moreira Pinto<\/td>\n<td style=\"width: 22.357%; text-align: right; height: 56px;\">\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 1168<\/td>\n<\/tr>\n<tr style=\"height: 56px;\">\n<td style=\"width: 59.2721%; height: 56px;\">Diretoria de Patrim\u00f4nio: Nara Maria da Silva<\/td>\n<td style=\"width: 22.357%; text-align: right; height: 56px;\">3147<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<ol>\n<li>b) Conselho Deliberativo<\/li>\n<\/ol>\n<table>\n<tbody>\n<tr>\n<td><b>Candidato<\/b><\/td>\n<td><b>Matr\u00edcula ELASE<\/b><\/td>\n<\/tr>\n<tr>\n<td>Edmilson Machado<\/td>\n<td style=\"text-align: right;\">\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 3363<\/td>\n<\/tr>\n<tr>\n<td>Antonio Rodrigues de Matos<\/td>\n<td style=\"text-align: right;\">\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 691<\/td>\n<\/tr>\n<tr>\n<td>Ronaldo Ferreira<\/td>\n<td style=\"text-align: right;\">\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 7375<\/td>\n<\/tr>\n<tr>\n<td>Vilmar Julio Felisbino<\/td>\n<td style=\"text-align: right;\">\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 1878<\/td>\n<\/tr>\n<tr>\n<td>Pedro Domingos Damazio<\/td>\n<td style=\"text-align: right;\">\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 7473<\/td>\n<\/tr>\n<tr>\n<td>Adilson de Souza Mello<\/td>\n<td style=\"text-align: right;\">\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 83<\/td>\n<\/tr>\n<tr>\n<td>Liberto da Concei\u00e7\u00e3o Gon\u00e7alves<\/td>\n<td style=\"text-align: right;\">\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 246<\/td>\n<\/tr>\n<tr>\n<td>Ilmar Goltara Gomes<\/td>\n<td style=\"text-align: right;\">\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 3714<\/td>\n<\/tr>\n<tr>\n<td>Lourival da Silva<\/td>\n<td style=\"text-align: right;\">\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 2991<\/td>\n<\/tr>\n<tr>\n<td>Carlos\u00a0 Guilherme Rocha dos Santos<\/td>\n<td style=\"text-align: right;\">\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 151<\/td>\n<\/tr>\n<tr>\n<td>Vasco Cardoso do Nascimento<\/td>\n<td style=\"text-align: right;\">\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 278<\/td>\n<\/tr>\n<tr>\n<td>Telmo Renato Lopes dos Santos<\/td>\n<td style=\"text-align: right;\">\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 1176<\/td>\n<\/tr>\n<tr>\n<td>Marcos Cruz de Aguiar<\/td>\n<td style=\"text-align: right;\">\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 2245<\/td>\n<\/tr>\n<tr>\n<td>Gilson Lu\u00eds Crestani<\/td>\n<td style=\"text-align: right;\">\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 1988<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<ol>\n<li>c) Conselho Fiscal<\/li>\n<\/ol>\n<table>\n<tbody>\n<tr>\n<td><b>Candidato<\/b><\/td>\n<td><b>Matr\u00edcula ELASE<\/b><\/td>\n<\/tr>\n<tr>\n<td>Altino Vieira<\/td>\n<td style=\"text-align: right;\">\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 1693<\/td>\n<\/tr>\n<tr>\n<td>Tadeu Schivinski<\/td>\n<td style=\"text-align: right;\">\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 1867<\/td>\n<\/tr>\n<tr>\n<td>Pedro Pereira Gomes<\/td>\n<td style=\"text-align: right;\">\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 0828<\/td>\n<\/tr>\n<tr>\n<td>Roberto Antonio Bertocco<\/td>\n<td style=\"text-align: right;\">\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 621<\/td>\n<\/tr>\n<tr>\n<td>Nivaldo Eduardo Fermino<\/td>\n<td style=\"text-align: right;\">\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 7327<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<p>Assim, esta Comiss\u00e3o Eleitoral informa que est\u00e1 aberto o prazo para interposi\u00e7\u00e3o de recursos, conforme estabelecido no Regulamento Geral da Elei\u00e7\u00e3o, cap\u00edtulo II \u2013 Pedido de Registro, devendo os interessados protocolarem os referidos recursos, at\u00e9 \u00e0s 18h do dia 22\/03\/2023, junto \u00e0 secretaria da ELASE.<\/p>\n<p>&nbsp;<\/p>\n<p><b>Aurino Machado<\/b><\/p>\n<p><b>Presidente da Comiss\u00e3o Eleitoral<\/b><\/p>\n<p>&nbsp;<\/p>\n<p><b>Carlos Alberto de Souza<\/b><\/p>\n<p><b>Secret\u00e1rio da Comiss\u00e3o Eleitoral<\/b><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: right;\"><b>Florian\u00f3polis, 16 de mar\u00e7o de 2023.<\/b><\/p>\n<p>&nbsp;<\/p>\n<h4><b>O documento original assinado pela Comiss\u00e3o Eleitoral encontra-se \u00e0 disposi\u00e7\u00e3o na Secretaria do Clube.<\/b><\/h4>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/www.elase.com.br\/blog\/eleicoes-elase-comunicado-1-2\/\"><b>Elei\u00e7\u00f5es ELASE: Veja o cronograma do processo eleitoral e as premissas para participar<\/b><\/a><\/p>\n<p><a href=\"https:\/\/www.elase.com.br\/blog\/eleicoes-para-o-trienio-2023-2026-regulamento-geral\/\"><b>Elei\u00e7\u00f5es para o Tri\u00eanio 2023\/2026 \u2013 REGULAMENTO GERAL<\/b><\/a><\/p>\n<p><a href=\"https:\/\/www.elase.com.br\/blog\/eleicoes-elase-comunicado-2-comissao-eleitoral\/\"><b>Elei\u00e7\u00f5es ELASE: COMUNICADO 2 \u2013 Comiss\u00e3o Eleitoral<\/b><\/a><\/p>\n<p><strong><a href=\"https:\/\/www.elase.com.br\/blog\/eleicoes-elase-homologacao-final-das-candidaturas\/\">Elei\u00e7\u00f5es ELASE: COMUNICADO 4 \u2013 Homologa\u00e7\u00e3o final das Candidaturas e in\u00edcio do Per\u00edodo Eleitoral<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A COMISS\u00c3O ELEITORAL designada pelo Conselho Deliberativo da ELASE, nos termos do Regulamento Geral das Elei\u00e7\u00f5es, comunica aos associados que no dia [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":1073,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[8],"tags":[],"class_list":["post-1072","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-elase"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Elei\u00e7\u00f5es ELASE \u2013 2023\/2026: COMUNICADO 3<\/title>\n<meta name=\"description\" content=\"Elei\u00e7\u00f5es ELASE tri\u00eanio 2023-2026 | Inscri\u00e7\u00f5es encerradas. Confira a rela\u00e7\u00e3o das candidaturas e seus respectivos cargos.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.elase.com.br\/blog\/eleicoes-elase-2023-2026-comunicado-3\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Elei\u00e7\u00f5es ELASE \u2013 2023\/2026: COMUNICADO 3\" \/>\n<meta property=\"og:description\" content=\"Elei\u00e7\u00f5es ELASE tri\u00eanio 2023-2026 | Inscri\u00e7\u00f5es encerradas. Confira a rela\u00e7\u00e3o das candidaturas e seus respectivos cargos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.elase.com.br\/blog\/eleicoes-elase-2023-2026-comunicado-3\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog da ELASE\" \/>\n<meta property=\"article:published_time\" content=\"2023-03-16T14:25:35+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-03-24T15:03:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.elase.com.br\/blog\/wp-content\/uploads\/sites\/2\/2023\/03\/post-blog-eleicoes-elase2-1024x486.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"486\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Elase\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Elase\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.elase.com.br\\\/blog\\\/eleicoes-elase-2023-2026-comunicado-3\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.elase.com.br\\\/blog\\\/eleicoes-elase-2023-2026-comunicado-3\\\/\"},\"author\":{\"name\":\"Elase\",\"@id\":\"https:\\\/\\\/www.elase.com.br\\\/blog\\\/#\\\/schema\\\/person\\\/c5648edcd86e91cabc5f62555421edce\"},\"headline\":\"Elei\u00e7\u00f5es ELASE \u2013 2023\\\/2026: COMUNICADO 3\",\"datePublished\":\"2023-03-16T14:25:35+00:00\",\"dateModified\":\"2023-03-24T15:03:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.elase.com.br\\\/blog\\\/eleicoes-elase-2023-2026-comunicado-3\\\/\"},\"wordCount\":416,\"image\":{\"@id\":\"https:\\\/\\\/www.elase.com.br\\\/blog\\\/eleicoes-elase-2023-2026-comunicado-3\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.elase.com.br\\\/blog\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2023\\\/03\\\/post-blog-eleicoes-elase2.png\",\"articleSection\":[\"ELASE\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.elase.com.br\\\/blog\\\/eleicoes-elase-2023-2026-comunicado-3\\\/\",\"url\":\"https:\\\/\\\/www.elase.com.br\\\/blog\\\/eleicoes-elase-2023-2026-comunicado-3\\\/\",\"name\":\"Elei\u00e7\u00f5es ELASE \u2013 2023\\\/2026: COMUNICADO 3\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.elase.com.br\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.elase.com.br\\\/blog\\\/eleicoes-elase-2023-2026-comunicado-3\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.elase.com.br\\\/blog\\\/eleicoes-elase-2023-2026-comunicado-3\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.elase.com.br\\\/blog\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2023\\\/03\\\/post-blog-eleicoes-elase2.png\",\"datePublished\":\"2023-03-16T14:25:35+00:00\",\"dateModified\":\"2023-03-24T15:03:23+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.elase.com.br\\\/blog\\\/#\\\/schema\\\/person\\\/c5648edcd86e91cabc5f62555421edce\"},\"description\":\"Elei\u00e7\u00f5es ELASE tri\u00eanio 2023-2026 | Inscri\u00e7\u00f5es encerradas. Confira a rela\u00e7\u00e3o das candidaturas e seus respectivos cargos.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.elase.com.br\\\/blog\\\/eleicoes-elase-2023-2026-comunicado-3\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.elase.com.br\\\/blog\\\/eleicoes-elase-2023-2026-comunicado-3\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.elase.com.br\\\/blog\\\/eleicoes-elase-2023-2026-comunicado-3\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.elase.com.br\\\/blog\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2023\\\/03\\\/post-blog-eleicoes-elase2.png\",\"contentUrl\":\"https:\\\/\\\/www.elase.com.br\\\/blog\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2023\\\/03\\\/post-blog-eleicoes-elase2.png\",\"width\":2560,\"height\":1215},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.elase.com.br\\\/blog\\\/eleicoes-elase-2023-2026-comunicado-3\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.elase.com.br\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Elei\u00e7\u00f5es ELASE \u2013 2023\\\/2026: COMUNICADO 3\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.elase.com.br\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.elase.com.br\\\/blog\\\/\",\"name\":\"Blog da ELASE\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.elase.com.br\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.elase.com.br\\\/blog\\\/#\\\/schema\\\/person\\\/c5648edcd86e91cabc5f62555421edce\",\"name\":\"Elase\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e04f303593dd0bee5fdbdc05ef63066d59e1a5bf61b911bf6653c92bfb86e392?s=96&r=g&d=https:\\\/\\\/www.elase.com.br\\\/blog\\\/wp-content\\\/plugins\\\/userswp\\\/assets\\\/images\\\/no_profile.png\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e04f303593dd0bee5fdbdc05ef63066d59e1a5bf61b911bf6653c92bfb86e392?s=96&r=g&d=https:\\\/\\\/www.elase.com.br\\\/blog\\\/wp-content\\\/plugins\\\/userswp\\\/assets\\\/images\\\/no_profile.png\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e04f303593dd0bee5fdbdc05ef63066d59e1a5bf61b911bf6653c92bfb86e392?s=96&r=g&d=https:\\\/\\\/www.elase.com.br\\\/blog\\\/wp-content\\\/plugins\\\/userswp\\\/assets\\\/images\\\/no_profile.png\",\"caption\":\"Elase\"},\"url\":\"https:\\\/\\\/www.elase.com.br\\\/blog\\\/author\\\/roberta\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Elei\u00e7\u00f5es ELASE \u2013 2023\/2026: COMUNICADO 3","description":"Elei\u00e7\u00f5es ELASE tri\u00eanio 2023-2026 | Inscri\u00e7\u00f5es encerradas. Confira a rela\u00e7\u00e3o das candidaturas e seus respectivos cargos.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.elase.com.br\/blog\/eleicoes-elase-2023-2026-comunicado-3\/","og_locale":"pt_BR","og_type":"article","og_title":"Elei\u00e7\u00f5es ELASE \u2013 2023\/2026: COMUNICADO 3","og_description":"Elei\u00e7\u00f5es ELASE tri\u00eanio 2023-2026 | Inscri\u00e7\u00f5es encerradas. Confira a rela\u00e7\u00e3o das candidaturas e seus respectivos cargos.","og_url":"https:\/\/www.elase.com.br\/blog\/eleicoes-elase-2023-2026-comunicado-3\/","og_site_name":"Blog da ELASE","article_published_time":"2023-03-16T14:25:35+00:00","article_modified_time":"2023-03-24T15:03:23+00:00","og_image":[{"width":1024,"height":486,"url":"https:\/\/www.elase.com.br\/blog\/wp-content\/uploads\/sites\/2\/2023\/03\/post-blog-eleicoes-elase2-1024x486.png","type":"image\/png"}],"author":"Elase","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Elase","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.elase.com.br\/blog\/eleicoes-elase-2023-2026-comunicado-3\/#article","isPartOf":{"@id":"https:\/\/www.elase.com.br\/blog\/eleicoes-elase-2023-2026-comunicado-3\/"},"author":{"name":"Elase","@id":"https:\/\/www.elase.com.br\/blog\/#\/schema\/person\/c5648edcd86e91cabc5f62555421edce"},"headline":"Elei\u00e7\u00f5es ELASE \u2013 2023\/2026: COMUNICADO 3","datePublished":"2023-03-16T14:25:35+00:00","dateModified":"2023-03-24T15:03:23+00:00","mainEntityOfPage":{"@id":"https:\/\/www.elase.com.br\/blog\/eleicoes-elase-2023-2026-comunicado-3\/"},"wordCount":416,"image":{"@id":"https:\/\/www.elase.com.br\/blog\/eleicoes-elase-2023-2026-comunicado-3\/#primaryimage"},"thumbnailUrl":"https:\/\/www.elase.com.br\/blog\/wp-content\/uploads\/sites\/2\/2023\/03\/post-blog-eleicoes-elase2.png","articleSection":["ELASE"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/www.elase.com.br\/blog\/eleicoes-elase-2023-2026-comunicado-3\/","url":"https:\/\/www.elase.com.br\/blog\/eleicoes-elase-2023-2026-comunicado-3\/","name":"Elei\u00e7\u00f5es ELASE \u2013 2023\/2026: COMUNICADO 3","isPartOf":{"@id":"https:\/\/www.elase.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.elase.com.br\/blog\/eleicoes-elase-2023-2026-comunicado-3\/#primaryimage"},"image":{"@id":"https:\/\/www.elase.com.br\/blog\/eleicoes-elase-2023-2026-comunicado-3\/#primaryimage"},"thumbnailUrl":"https:\/\/www.elase.com.br\/blog\/wp-content\/uploads\/sites\/2\/2023\/03\/post-blog-eleicoes-elase2.png","datePublished":"2023-03-16T14:25:35+00:00","dateModified":"2023-03-24T15:03:23+00:00","author":{"@id":"https:\/\/www.elase.com.br\/blog\/#\/schema\/person\/c5648edcd86e91cabc5f62555421edce"},"description":"Elei\u00e7\u00f5es ELASE tri\u00eanio 2023-2026 | Inscri\u00e7\u00f5es encerradas. Confira a rela\u00e7\u00e3o das candidaturas e seus respectivos cargos.","breadcrumb":{"@id":"https:\/\/www.elase.com.br\/blog\/eleicoes-elase-2023-2026-comunicado-3\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.elase.com.br\/blog\/eleicoes-elase-2023-2026-comunicado-3\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.elase.com.br\/blog\/eleicoes-elase-2023-2026-comunicado-3\/#primaryimage","url":"https:\/\/www.elase.com.br\/blog\/wp-content\/uploads\/sites\/2\/2023\/03\/post-blog-eleicoes-elase2.png","contentUrl":"https:\/\/www.elase.com.br\/blog\/wp-content\/uploads\/sites\/2\/2023\/03\/post-blog-eleicoes-elase2.png","width":2560,"height":1215},{"@type":"BreadcrumbList","@id":"https:\/\/www.elase.com.br\/blog\/eleicoes-elase-2023-2026-comunicado-3\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.elase.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Elei\u00e7\u00f5es ELASE \u2013 2023\/2026: COMUNICADO 3"}]},{"@type":"WebSite","@id":"https:\/\/www.elase.com.br\/blog\/#website","url":"https:\/\/www.elase.com.br\/blog\/","name":"Blog da ELASE","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.elase.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/www.elase.com.br\/blog\/#\/schema\/person\/c5648edcd86e91cabc5f62555421edce","name":"Elase","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/e04f303593dd0bee5fdbdc05ef63066d59e1a5bf61b911bf6653c92bfb86e392?s=96&r=g&d=https:\/\/www.elase.com.br\/blog\/wp-content\/plugins\/userswp\/assets\/images\/no_profile.png","url":"https:\/\/secure.gravatar.com\/avatar\/e04f303593dd0bee5fdbdc05ef63066d59e1a5bf61b911bf6653c92bfb86e392?s=96&r=g&d=https:\/\/www.elase.com.br\/blog\/wp-content\/plugins\/userswp\/assets\/images\/no_profile.png","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e04f303593dd0bee5fdbdc05ef63066d59e1a5bf61b911bf6653c92bfb86e392?s=96&r=g&d=https:\/\/www.elase.com.br\/blog\/wp-content\/plugins\/userswp\/assets\/images\/no_profile.png","caption":"Elase"},"url":"https:\/\/www.elase.com.br\/blog\/author\/roberta\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-07-21 23:59:42","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.elase.com.br\/blog\/wp-json\/wp\/v2\/posts\/1072","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.elase.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.elase.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.elase.com.br\/blog\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.elase.com.br\/blog\/wp-json\/wp\/v2\/comments?post=1072"}],"version-history":[{"count":6,"href":"https:\/\/www.elase.com.br\/blog\/wp-json\/wp\/v2\/posts\/1072\/revisions"}],"predecessor-version":[{"id":1091,"href":"https:\/\/www.elase.com.br\/blog\/wp-json\/wp\/v2\/posts\/1072\/revisions\/1091"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.elase.com.br\/blog\/wp-json\/wp\/v2\/media\/1073"}],"wp:attachment":[{"href":"https:\/\/www.elase.com.br\/blog\/wp-json\/wp\/v2\/media?parent=1072"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.elase.com.br\/blog\/wp-json\/wp\/v2\/categories?post=1072"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.elase.com.br\/blog\/wp-json\/wp\/v2\/tags?post=1072"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}